{"id":12061,"date":"2022-05-16T21:37:34","date_gmt":"2022-05-16T19:37:34","guid":{"rendered":"https:\/\/geoconsulting.eu\/?post_type=geo_casestudy&#038;p=12061"},"modified":"2022-05-16T21:42:21","modified_gmt":"2022-05-16T19:42:21","slug":"brico","status":"publish","type":"geo_casestudy","link":"https:\/\/geoconsulting.eu\/nl\/geo_casestudy\/brico\/","title":{"rendered":"Brico"},"content":{"rendered":"\n<p>De Brico-groep is de toonaangevende distributeur van doe-het-zelf-gerelateerde producten in Belgi\u00eb. De groep bestaat sinds 1973 en heeft nu meer dan 150 winkels in Belgi\u00eb, Luxemburg en Nederland onder de merken Brico, BricoCity en BricoPlanit.<\/p>\n\n\n\n<ul class=\"has-text-smaller-font-size wp-block-list\"><li>Realisatie van het ontwikkelingsplan, onderzoeken naar potenti\u00eble omzet, impactstudies, procedures voor vergunningen voor commerci\u00eble vestigingen<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>De Brico-groep is de toonaangevende distributeur van doe-het-zelf-gerelateerde producten in Belgi\u00eb. De groep bestaat sinds 1973 en heeft nu meer dan 150 winkels in Belgi\u00eb, Luxemburg en Nederland onder de merken Brico, BricoCity en BricoPlanit. Realisatie van het ontwikkelingsplan, onderzoeken naar potenti\u00eble omzet, impactstudies, procedures voor vergunningen voor commerci\u00eble vestigingen<\/p>\n","protected":false},"featured_media":12062,"menu_order":3,"template":"","meta":{"_acf_changed":false},"class_list":["post-12061","geo_casestudy","type-geo_casestudy","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/geoconsulting.eu\/nl\/wp-json\/wp\/v2\/geo_casestudy\/12061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/geoconsulting.eu\/nl\/wp-json\/wp\/v2\/geo_casestudy"}],"about":[{"href":"https:\/\/geoconsulting.eu\/nl\/wp-json\/wp\/v2\/types\/geo_casestudy"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/geoconsulting.eu\/nl\/wp-json\/wp\/v2\/media\/12062"}],"wp:attachment":[{"href":"https:\/\/geoconsulting.eu\/nl\/wp-json\/wp\/v2\/media?parent=12061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}